{"id":20563,"date":"2026-05-15T16:16:00","date_gmt":"2026-05-15T14:16:00","guid":{"rendered":"https:\/\/www.kurtsafari.com\/?page_id=20563"},"modified":"2026-05-19T12:11:25","modified_gmt":"2026-05-19T10:11:25","slug":"kruger-safari-packages","status":"publish","type":"page","link":"https:\/\/www.kurtsafari.com\/uk\/kruger-safari-packages\/","title":{"rendered":"Kruger Safari Packages"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"20563\" class=\"elementor elementor-20563\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e88e1b4 e-flex e-con-boxed e-con e-parent\" data-id=\"e88e1b4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9446ace elementor-widget elementor-widget-heading\" data-id=\"9446ace\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">All Inclusive Kruger Safari Packages<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f39a917 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"f39a917\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Discover expertly guided all inclusive Kruger safari packages with Big 5 game drives, accommodation, transfers, and unforgettable wildlife experiences in the Kruger National Park.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-824795c e-flex e-con-boxed e-con e-parent\" data-id=\"824795c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d4f434 elementor-widget elementor-widget-heading\" data-id=\"9d4f434\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Experience the Best Kruger Park Safaris<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d4463a5 e-con-full e-flex e-con e-child\" data-id=\"d4463a5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b91f45b e-con-full e-flex e-con e-child\" data-id=\"b91f45b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f89041c elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"f89041c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Experience the beauty of South Africa\u2019s most iconic wildlife destination with our all inclusive Kruger safari packages designed for comfort, convenience, and unforgettable safari adventures.<\/p><p>At Kurt Safari, we offer expertly guided Kruger National Park safari packages that include everything you need for a seamless safari experience, from accommodation and open vehicle game drives to park fees, transfers, and experienced safari guides.<\/p><p>Whether you are looking for a short 3 day Kruger safari package, a luxury safari getaway, or a fully guided multi day safari from Johannesburg, our safari packages cater to every type of traveller.<\/p><p>From thrilling <a href=\"https:\/\/www.kurtsafari.com\/uk\/animals-in-kruger-national-park\/\">Big 5<\/a> encounters to breathtaking African landscapes, our guided Kruger safari packages are designed to help you experience the very best of the Kruger National Park.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f4ab7f6 e-con-full e-flex e-con e-child\" data-id=\"f4ab7f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ac1e52 elementor-widget elementor-widget-image\" data-id=\"4ac1e52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"576\" src=\"https:\/\/www.kurtsafari.com\/wp-content\/uploads\/2025\/04\/3-Day-Best-of-Kruger-Private-safari-1-1024x737.webp\" class=\"attachment-large size-large wp-image-11947\" alt=\"Safari tourists in open vehicle watch elephant crossing dirt road in Kruger National Park.\" srcset=\"https:\/\/www.kurtsafari.com\/wp-content\/uploads\/2025\/04\/3-Day-Best-of-Kruger-Private-safari-1-1024x737.webp 1024w, https:\/\/www.kurtsafari.com\/wp-content\/uploads\/2025\/04\/3-Day-Best-of-Kruger-Private-safari-1-300x216.webp 300w, https:\/\/www.kurtsafari.com\/wp-content\/uploads\/2025\/04\/3-Day-Best-of-Kruger-Private-safari-1-768x553.webp 768w, https:\/\/www.kurtsafari.com\/wp-content\/uploads\/2025\/04\/3-Day-Best-of-Kruger-Private-safari-1-18x12.webp 18w, https:\/\/www.kurtsafari.com\/wp-content\/uploads\/2025\/04\/3-Day-Best-of-Kruger-Private-safari-1.webp 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-06a0ea4 e-flex e-con-boxed e-con e-parent\" data-id=\"06a0ea4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-be0b9ae e-con-full e-flex e-con e-child\" data-id=\"be0b9ae\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35969a3 elementor-widget elementor-widget-heading\" data-id=\"35969a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Explore Our Kruger Safari Packages<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cde9693 e-con-full e-flex e-con e-child\" data-id=\"cde9693\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-43a7cdd e-con-full e-flex e-con e-child\" data-id=\"43a7cdd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fc25f9f e-con-full e-flex e-con e-child\" data-id=\"fc25f9f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e7caeee elementor-widget elementor-widget-heading\" data-id=\"e7caeee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3 Day Kruger Safari Packages<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-969c7f0 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"969c7f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Our 3 day Kruger safari packages are perfect for travellers looking to experience the Kruger National Park within a shorter timeframe while still enjoying incredible wildlife sightings and guided safari experiences.<\/p><p>These safari packages are ideal for:<\/p><ul><li>Weekend safari getaways<\/li><li>First-time visitors to South Africa<\/li><li>Couples and small groups<\/li><li>Travellers departing from Johannesburg<\/li><\/ul><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24f9558 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"24f9558\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.kurtsafari.com\/uk\/3-day-safari-packages\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View 3 Day Kruger Safari Packages<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e1e52cf e-con-full e-flex e-con e-child\" data-id=\"e1e52cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-25be6c6 e-con-full e-flex e-con e-child\" data-id=\"25be6c6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c22f93 elementor-widget elementor-widget-heading\" data-id=\"2c22f93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4 Day Kruger Safari Packages<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e8e5d7 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"3e8e5d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>4 day Kruger safari package offers a more immersive safari experience with additional game drives, more wildlife viewing opportunities, and extra time to explore the beauty of the Kruger National Park.<\/p><p>Perfect for travellers wanting:<\/p><ul><li>Extended safari experiences<\/li><li>More Big 5 viewing opportunities<\/li><li>Comfortable all inclusive safari travel<\/li><li>A balance between adventure and relaxation<br \/><br \/><\/li><\/ul><p>These guided safari packages allow guests to fully experience the diverse wildlife and landscapes that make Kruger one of Africa\u2019s leading safari destinations.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b9b8f4 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"6b9b8f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.kurtsafari.com\/uk\/4-day-safari-packages\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Explore 4 Day Kruger Safari Packages<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a59cb6c e-con-full e-flex e-con e-child\" data-id=\"a59cb6c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-223dd24 e-con-full e-flex e-con e-child\" data-id=\"223dd24\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3c06a2e e-con-full e-flex e-con e-child\" data-id=\"3c06a2e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b2aaa8c e-con-full e-flex e-con e-child\" data-id=\"b2aaa8c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-df28125 elementor-widget elementor-widget-heading\" data-id=\"df28125\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5 Day Kruger Safari Packages<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-002765d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"002765d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Our 5 day Kruger safari packages provide the ultimate all inclusive safari experience with extended game viewing, luxury accommodation options, and unforgettable wildlife encounters.<\/p><p>Ideal for:<\/p><ul><li>International travellers<\/li><li>Wildlife photographers<\/li><li>Honeymoon safaris<\/li><li>Luxury safari experiences<\/li><li>Families and private groups<br \/><br \/><\/li><\/ul><p>These longer safari packages provide greater opportunities to explore different regions of the park while maximising your chances of spotting the Big 5.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a09a630 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"a09a630\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.kurtsafari.com\/uk\/5-day-safari-packages\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discover 5 Day Kruger Safaris<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c70809 e-flex e-con-boxed e-con e-parent\" data-id=\"2c70809\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-beb87ae e-con-full e-flex e-con e-child\" data-id=\"beb87ae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6432b34 e-con-full e-flex e-con e-child\" data-id=\"6432b34\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8dbc661 e-con-full e-flex e-con e-child\" data-id=\"8dbc661\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b2a1bcf elementor-widget elementor-widget-heading\" data-id=\"b2a1bcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">What Is Included in Our All Inclusive Kruger Safari Packages?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7224e81 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7224e81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Our all inclusive Kruger safari packages are designed to provide a stress-free safari experience with everything arranged for you before arrival.<\/p><p>Depending on your selected safari package, inclusions may include:<\/p><ul><li>Guided open vehicle game drives<\/li><li>Luxury or standard accommodation<\/li><li>Daily safari activities<\/li><li>Kruger National Park entry fees<\/li><li>Transfers from Johannesburg or OR Tambo Airport<\/li><li>Breakfasts and dinners<\/li><li>Experienced safari guides<\/li><li>Air-conditioned transport<\/li><li>Pickup and drop-off services<br \/><br \/><\/li><\/ul><p>Whether you choose a budget safari package or a luxury safari experience, every tour is professionally guided and carefully planned from start to finish.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-97fe52c e-flex e-con-boxed e-con e-parent\" data-id=\"97fe52c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0648e88 e-con-full e-flex e-con e-child\" data-id=\"0648e88\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d7ae69 elementor-widget elementor-widget-heading\" data-id=\"3d7ae69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Choose the Right Kruger Safari Package<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e6f40b e-con-full e-flex e-con e-child\" data-id=\"7e6f40b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-773afb2 e-con-full e-flex e-con e-child\" data-id=\"773afb2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64c2114 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"64c2114\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Classic Kruger Safari Packages<\/h3><p>Our classic Kruger safari packages offer incredible wildlife experiences at affordable rates without compromising on quality or comfort.<\/p><p><strong>Perfect for:<\/strong><\/p><ul><li>Backpackers<\/li><li>Students<\/li><li>Budget-conscious travellers<\/li><li>Small groups and families<\/li><\/ul><p><strong>Budget safari packages may include:<\/strong><\/p><ul><li>Shared safari vehicles<\/li><li>Comfortable lodge accommodation<\/li><li>Scheduled safari departures<\/li><li>Guided game drives<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecca4b5 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"ecca4b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.kurtsafari.com\/uk\/kruger-safari\/classic-safari\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discover Classic Kruger Safari Packages<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-82c6d0c e-con-full e-flex e-con e-child\" data-id=\"82c6d0c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5368767 e-con-full e-flex e-con e-child\" data-id=\"5368767\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-37a419a e-con-full e-flex e-con e-child\" data-id=\"37a419a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c9086f9 e-con-full e-flex e-con e-child\" data-id=\"c9086f9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d3a55e elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2d3a55e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Luxury Kruger Safari Packages<\/h3><p>Our luxury Kruger safari packages combine world-class safari experiences with premium accommodation, exceptional service, and unforgettable wildlife encounters.<\/p><p><strong>Luxury safari features may include:<\/strong><\/p><ul><li>Luxury safari lodges<\/li><li>Private safari experiences<\/li><li>Gourmet dining<\/li><li>Premium safari vehicles<\/li><li>Airport transfers<\/li><li>Exclusive safari routes<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c04d02 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"8c04d02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.kurtsafari.com\/uk\/kruger-safari\/luxury-kruger-safaris\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discover Luxury Kruger Safari Packages<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f7dcf6 e-con-full e-flex e-con e-child\" data-id=\"5f7dcf6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-87439b7 e-con-full e-flex e-con e-child\" data-id=\"87439b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b5bfc69 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b5bfc69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Private Kruger Safari Packages<\/h3><p>For travellers seeking a more exclusive safari experience, we also offer private Kruger safari packages tailored to couples, families, photographers, and small groups.<\/p><p><strong>Private safari options may include:<\/strong><\/p><ul><li>Private safari vehicles<\/li><li>Flexible safari schedules<\/li><li>Custom safari itineraries<\/li><li>Exclusive wildlife experiences<\/li><li>Luxury lodge accommodation<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa31c22 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"fa31c22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.kurtsafari.com\/uk\/kruger-safari\/private-luxury-safaris\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discover Private Kruger Safari Packages<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-84e8f12 e-con-full e-flex e-con e-child\" data-id=\"84e8f12\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40b5152 e-flex e-con-boxed e-con e-parent\" data-id=\"40b5152\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1dc97a2 e-con-full e-flex e-con e-child\" data-id=\"1dc97a2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-469c2cd elementor-widget elementor-widget-text-editor\" data-id=\"469c2cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>Why Choose an All Inclusive Kruger Safari?<\/h2><p>Choosing an all inclusive Kruger safari package removes the stress of organising accommodation, transport, park fees, and safari activities separately.<\/p><p>With Kurt Safari, every detail is professionally arranged to provide a smooth and immersive safari experience from the moment your journey begins.<\/p><p>Benefits of our guided safari packages include:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5656c5b elementor-icon-list--layout-inline elementor-widget__width-initial elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5656c5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Convenient travel planning<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Experienced safari guides<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Carefully selected accommodation<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Better wildlife viewing opportunities<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Hassle-free safari experiences<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Excellent value for international travellers<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Safe and professionally guided safari tours<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfaae11 elementor-widget elementor-widget-text-editor\" data-id=\"dfaae11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Whether you are travelling solo, as a couple, with family, or in a group, our Kruger safari packages provide unforgettable experiences in one of Africa\u2019s greatest wildlife destinations.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a520f0 e-flex e-con-boxed e-con e-parent\" data-id=\"6a520f0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-16ecde5 e-con-full e-flex e-con e-child\" data-id=\"16ecde5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-52f1ce3 e-con-full e-flex e-con e-child\" data-id=\"52f1ce3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6296cb2 e-con-full e-flex e-con e-child\" data-id=\"6296cb2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c01dcd elementor-widget elementor-widget-heading\" data-id=\"5c01dcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Plan Your Kruger Safari from Johannesburg<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bd0f0d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4bd0f0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Many of our all inclusive Kruger safari packages include convenient departures from Johannesburg and OR Tambo International Airport, making travel planning simple for both local and international travellers.<\/p><p><strong>Our Kruger safaris from Johannesburg include:<\/strong><\/p><ul><li>Comfortable transport<\/li><li>Guided safari experiences<\/li><li>Accommodation<\/li><li>Park entry fees<\/li><li>Multi day safari itineraries<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a3bf95 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"8a3bf95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.kurtsafari.com\/uk\/kruger-park-safaris\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View Kruger Safaris from Johannesburg<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9abdea7 e-flex e-con-boxed e-con e-parent\" data-id=\"9abdea7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-410156f elementor-widget elementor-widget-heading\" data-id=\"410156f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Frequently Asked Questions<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5937619 elementor-widget elementor-widget-spacer\" data-id=\"5937619\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c88c0b elementor-widget elementor-widget-n-accordion\" data-id=\"3c88c0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6340\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-6340\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> What is included in an all inclusive Kruger safari package? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6340\" class=\"elementor-element elementor-element-299b169 e-con-full e-flex e-con e-child\" data-id=\"299b169\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-96f39d5 elementor-widget elementor-widget-text-editor\" data-id=\"96f39d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Most all inclusive Kruger safari packages include accommodation, guided game drives, park fees, selected meals, and transfers from Johannesburg or OR Tambo Airport.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6341\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6341\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> How much does a Kruger safari package cost? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6341\" class=\"elementor-element elementor-element-a37fb67 e-con-full e-flex e-con e-child\" data-id=\"a37fb67\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb96b17 elementor-widget elementor-widget-text-editor\" data-id=\"cb96b17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Pricing depends on safari duration, accommodation type, and whether you choose a budget, standard, private, or luxury safari package.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6342\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6342\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> What is the best length for a Kruger safari? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6342\" class=\"elementor-element elementor-element-2c02b5e e-con-full e-flex e-con e-child\" data-id=\"2c02b5e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e891fce elementor-widget elementor-widget-text-editor\" data-id=\"e891fce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>A 4 or 5 day safari package is generally recommended for the best wildlife viewing opportunities and overall safari experience.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6343\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6343\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Are Kruger safari packages suitable for families? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6343\" class=\"elementor-element elementor-element-ad140fa e-con-full e-flex e-con e-child\" data-id=\"ad140fa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d853a5e elementor-widget elementor-widget-text-editor\" data-id=\"d853a5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Yes. Many of our guided safari packages are family-friendly and suitable for couples, children, and small groups.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6344\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6344\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Can I book a private Kruger safari package? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6344\" class=\"elementor-element elementor-element-ea7b938 e-con-full e-flex e-con e-child\" data-id=\"ea7b938\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f6e320c elementor-widget elementor-widget-text-editor\" data-id=\"f6e320c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Yes. We offer private safari packages for travellers looking for exclusive and personalised safari experiences in the Kruger National Park.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-45cb805 e-flex e-con-boxed e-con e-parent\" data-id=\"45cb805\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b2ed66 elementor-widget elementor-widget-heading\" data-id=\"5b2ed66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Book Your All Inclusive Kruger Safari Package<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54c4528 elementor-widget elementor-widget-text-editor\" data-id=\"54c4528\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Experience the magic of the Kruger National Park with expertly guided all inclusive safari packages designed for unforgettable wildlife encounters.<\/p><p>Whether you are looking for a luxury safari, a private Big 5 experience, or a guided Kruger safari package from Johannesburg, Kurt Safari offers safari adventures tailored to every traveller.<\/p><p>Start planning your Kruger safari adventure today.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>All Inclusive Kruger Safari Packages Discover expertly guided all inclusive Kruger safari packages with Big 5 game drives, accommodation, transfers, and unforgettable wildlife experiences in the Kruger National Park. Experience the Best Kruger Park Safaris Experience the beauty of South Africa\u2019s most iconic wildlife destination with our all inclusive Kruger safari packages designed for comfort, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":17221,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-20563","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kurtsafari.com\/uk\/wp-json\/wp\/v2\/pages\/20563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kurtsafari.com\/uk\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.kurtsafari.com\/uk\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.kurtsafari.com\/uk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kurtsafari.com\/uk\/wp-json\/wp\/v2\/comments?post=20563"}],"version-history":[{"count":0,"href":"https:\/\/www.kurtsafari.com\/uk\/wp-json\/wp\/v2\/pages\/20563\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.kurtsafari.com\/uk\/wp-json\/wp\/v2\/pages\/17221"}],"wp:attachment":[{"href":"https:\/\/www.kurtsafari.com\/uk\/wp-json\/wp\/v2\/media?parent=20563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}