{"id":9542,"date":"2020-02-03T00:00:00","date_gmt":"2020-02-02T22:00:00","guid":{"rendered":"https:\/\/www.kurtsafari.com\/male-baboon-shows-unusual-maternal-side-to-lion-cub\/"},"modified":"2025-06-29T14:39:32","modified_gmt":"2025-06-29T12:39:32","slug":"il-babbuino-maschio-mostra-un-insolito-lato-materno-al-cucciolo-di-leone","status":"publish","type":"post","link":"https:\/\/www.kurtsafari.com\/it\/kruger-national-park-news\/current-news\/male-baboon-unusual-maternal-side-lion-cub\/","title":{"rendered":"Babbuino maschio mostra un insolito lato materno verso un cucciolo di leone"},"content":{"rendered":"<p>Sabato mattina sono entrato nel Kruger Park abbastanza presto e stavo andando a Skukuza perch\u00e9 avevo un appuntamento per colazione. Lavoro nel Kruger, guidando safari nel Kruger Park e gestendo\u00a0<a href=\"https:\/\/www.kurtsafari.com\/it\/\">www.kurtsafari.com<\/a><u>,<\/u>\u00a0per gli ultimi 10 anni e passo la maggior parte della settimana in ufficio.<\/p>\n<p>I fine settimana sono il mio momento per prendere la mia macchina fotografica e addentrarmi nella boscaglia, e stavo parlando con il mio manager proprio la settimana prima e gli avevo detto che non avevo avuto molta fortuna ultimamente. Ma le cose stavano per cambiare.<\/p>\n<p>Sono andato in una zona che sapevo essere molto attiva e con molti avvistamenti di leoni di recente, e mi sono imbattuto in una mandria di babbuini che erano davvero eccitati e giocosi, il che non era insolito a quest'ora del mattino.<\/p>\n<p>C'era un altro veicolo all'avvistamento dei babbuini e si parlava di un cucciolo di leone visto tra il branco.<\/p>\n<p>Dopo aver atteso per un po', notammo che un babbuino, che pensavamo fosse una femmina, stava trasportando un cucciolo di leone che io presi per morto. Quest'area \u00e8 caratterizzata da grandi massi di granito e colline ed \u00e8 nota per i leopardi e i leoni che nascondono i loro cuccioli appena nati tra i koppies (piccole colline). Il babbuino aveva attraversato la strada e si era arrampicato su un vicino albero di Marula quando allora notammo che il cucciolo era vivo.<\/p>\n<h3>Il babbuino stava toelettando il cucciolo di leone come se fosse un membro del branco. I babbuini maschi fanno molta toelettatura, ma la cura e la toelettatura che questo babbuino maschio ha dato al cucciolo erano le stesse di quelle che una femmina d\u00e0 a un cucciolo di babbuino.<\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.kurtsafari.com\/wp-content\/uploads\/2020\/02\/LB1.webp\" alt=\"\" \/><\/p>\n<p>Il resto del branco si abitu\u00f2 alla presenza del cucciolo di leone. Il maschio di babbuino si spostava tra i rami del Marula, toelettando e trasportando il cucciolo per un lungo periodo di tempo.<\/p>\n<p>Il cucciolo sembrava molto stanco e, sebbene non fossero visibili ferite immediate, potrebbe aver riportato lesioni interne, poich\u00e9 i cuccioli di leone non sono abituati a essere trasportati in questo modo. I babbuini sono animali molto forti e, dato che erano tutti eccitati per il cucciolo di leone e all'inizio litigavano per averlo, potrebbe essersi ferito nell'eccitazione.<\/p>\n<p>Erano gi\u00e0 circa le 8 del mattino e le temperature stavano gi\u00e0 raggiungendo i 30 gradi. La disidratazione sembrava che stesse iniziando a farsi sentire per il cucciolo. I babbuini hanno iniziato a spostarsi pi\u00f9 all'interno della boscaglia e ho lasciato la scena quando sono arrivati altri veicoli, per dare spazio a chi voleva vedere cosa stava succedendo.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.kurtsafari.com\/wp-content\/uploads\/2020\/02\/LB2.webp\" alt=\"\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.kurtsafari.com\/wp-content\/uploads\/2020\/02\/LB3.webp\" alt=\"\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.kurtsafari.com\/wp-content\/uploads\/2020\/02\/LB4.webp\" alt=\"\" \/><\/p>\n<h2><strong>Kurt Schultz acceso <a href=\"https:\/\/www.jacarandafm.com\/breakfast-martin-bester\/rafiki-and-simba-adult-baboon-steals-lion-cub-kruger-national-park\/\" target=\"_blank\" rel=\"noopener\">Colazione con Martin Bester<\/a><\/strong><\/h2>\n<p>Ascolta di pi\u00f9 sulla storia:<\/p>\n<h3>Nei 20 anni di guida turistica nell'Africa meridionale e orientale, e dopo essere stato nel Parco Kruger per quasi 20 anni, ho visto cuccioli di leopardo essere brutalmente uccisi dai babbuini e ho visto babbuini uccidere cuccioli di leone, ma non ho mai visto un babbuino mostrare tale cura e attenzione verso un cucciolo di leone.<\/h3>\n<p>Sfortunatamente, non vedo alcuna possibilit\u00e0 di sopravvivenza per questo povero cucciolo; il branco di babbuini era numeroso e un leone non sarebbe stato in grado di recuperare il cucciolo. La natura \u00e8 crudele nei momenti migliori e la sopravvivenza di un giovane predatore non \u00e8 sempre una garanzia. Il cucciolo di leone rappresenter\u00e0 una minaccia per i babbuini man mano che invecchia, quindi, naturalmente, le possibilit\u00e0 di sopravvivenza in questa giovane et\u00e0 sono minime.<\/p>\n<p>Quando si vede qualcosa del genere, ci si preoccupa per il leone e si spera che cresca e viva una vita selvatica e libera, ma purtroppo la natura ha i suoi modi e noi non possiamo interferire.<\/p>\n<p>Dobbiamo mantenere il Parco Kruger selvaggio e semplice. Questi erano i desideri del primo guardiano e protettore del parco, James Stevenson-Hamilton. E nel Kruger, dove la fauna selvatica vaga liberamente tra i veicoli, si capisce perch\u00e9 debba rimanere cos\u00ec.<\/p>\n<h3>Detto questo, questo rimarr\u00e0 uno dei miei avvistamenti pi\u00f9 interessanti e memorabili.<\/h3>","protected":false},"excerpt":{"rendered":"<p>On Saturday morning I entered the Kruger Park fairly early and was on my way to Skukuza as I had a breakfast appointment planned. I have been working in the Kruger, guiding Kruger Park safaris and running\u00a0www.kurtsafari.com,\u00a0for the last 10 years and I spend most of the week in the office. Weekends are my time [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9548,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[132,119],"tags":[],"class_list":["post-9542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-current-news","category-kruger-national-park-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/posts\/9542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/comments?post=9542"}],"version-history":[{"count":0,"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/posts\/9542\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/media\/9548"}],"wp:attachment":[{"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/media?parent=9542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/categories?post=9542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/tags?post=9542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}