{"id":10065,"date":"2021-11-03T00:00:00","date_gmt":"2021-11-02T22:00:00","guid":{"rendered":"https:\/\/www.kurtsafari.com\/gods-window-skywalk\/"},"modified":"2025-06-29T13:18:42","modified_gmt":"2025-06-29T11:18:42","slug":"finestra-degli-dei-skywalk","status":"publish","type":"post","link":"https:\/\/www.kurtsafari.com\/it\/blog\/2021\/11\/03\/gods-window-skywalk\/","title":{"rendered":"Finestra del Cielo di Dio"},"content":{"rendered":"<h2>Vieni a esplorare il God's Window Skywalk<\/h2>\n<p>In alto tra le nuvole, attorno al villaggio di Graskop, si trova un luogo ultraterreno. Conosciuto come God\u2019s Window, un breve sentiero escursionistico porta gli ospiti sul bordo di una vetta nelle montagne dell'escarpment e svela uno spettacolo che rimarr\u00e0 con loro per sempre. La vista dall'alto pu\u00f2 togliere il fiato e, anche senza una macchina fotografica in mano, non dimenticherete mai la bellezza visibile da questo punto panoramico.<\/p>\n<p>Per molto tempo, l'unico modo per vivere God's Window era attraverso pochi punti panoramici, che erano spesso sovraffollati di turisti.<\/p>\n<h3>Ma ora, questa vecchia attrazione del Panorama Route \u00e8 pronta per una ristrutturazione.<\/h3>\n<p>Recentemente \u00e8 stato annunciato che God's Window diventer\u00e0 il sito del primissimo skywalk del Sudafrica.<\/p>\n<p>Il progetto dovrebbe essere inaugurato nel 2023 e sar\u00e0 pi\u00f9 alto degli altri skywalk al mondo, ovvero il Grand Canyon Skywalk e il Ponte di Vetro di Zhangjiajie. Il God\u2019s Window Skywalk vedr\u00e0 gli ospiti trovarsi a circa 900 metri dal suolo, un'altezza davvero vertiginosa!<\/p>\n<p>Poich\u00e9 lo skywalk sar\u00e0 realizzato con una passerella di vetro a sbalzo che sar\u00e0 sospesa sul bordo del punto panoramico God's Window, gli ospiti potranno godere per la prima volta di viste a 360 gradi del Lowveld sottostante. La passerella si estender\u00e0 per 12 metri dalla scogliera e sar\u00e0 larga 5 metri.<\/p>\n<p>Dato che l'area del Blyde River Canyon attira gi\u00e0 1 milione di viaggiatori ogni anno, questa caratteristica aggiuntiva sar\u00e0 un'attrazione molto gradita alla zona e si affiancher\u00e0 bene al Graskop Gorge lift, gi\u00e0 operativo.<\/p>\n<p>Quando il ponte sospeso sar\u00e0 completato, gli ospiti dovranno rimanere nell'area circa 1 o 2 giorni in pi\u00f9, se desiderano visitare tutte le attrazioni speciali che la zona ha da offrire.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.kurtsafari.com\/wp-content\/uploads\/2021\/11\/gods-window-panorama-route.webp\" alt=\"\" \/><\/p>\n<h3>Su God's Window<\/h3>\n<p>God's Window \u00e8 per eccellenza un'attrazione naturale. A parte una semplice area visitatori dove gli ospiti possono acquistare souvenir locali e usare il bagno, l'intera area comprende alcuni sentieri ben tenuti e vari punti panoramici che si trovano alla fine dei percorsi. L'area \u00e8 stata lasciata il pi\u00f9 naturale possibile, e questa sensazione di foresta pluviale fa parte dell'attrazione.<\/p>\n<p>God's Window fa parte della famosa Panorama Route, una delle destinazioni turistiche pi\u00f9 entusiasmanti del Sudafrica. Il percorso \u00e8 composto da foreste e cascate, nonch\u00e9 da antiche e bellissime citt\u00e0 dove gli ospiti della zona possono fermarsi per una pausa. Il percorso comprende anche il Blyde River Canyon, uno dei canyon pi\u00f9 grandi e antichi del mondo.<\/p>\n<p>La Panorama Route si trova sulla strada per il Kruger National Park e spesso fa parte di un <a href=\"https:\/\/www.kurtsafari.com\/it\/safari-e-tour-del-parco-nazionale-kruger\/il-meglio-dei-safari-di-gruppo-del-kruger\/\">Pacchetto safari al Kruger Park.<\/a> Safari come questi al Kruger sono spesso preferiti dagli ospiti che visitano l'area per la prima volta, poich\u00e9 offrono un po' di variet\u00e0 al viaggio.<\/p>\n<p>Se stai pianificando <a href=\"https:\/\/www.kurtsafari.com\/it\/\">Safari al Parco Kruger<\/a>, allora assicurati di includere un <a href=\"https:\/\/www.kurtsafari.com\/it\/safari-e-tour-del-parco-nazionale-kruger\/il-meglio-dei-safari-di-gruppo-del-kruger\/kruger-e-panorama-safari-di-4-giorni-in-piccolo-gruppo\/\">Panorama Route tour<\/a> nella tua selezione.<\/p>","protected":false},"excerpt":{"rendered":"<p>Come and explore God\u2019s Window Skywalk High up in the clouds around the village of Graskop lies a place that is otherworldly. Known as God\u2019s Window, a short hiking trail takes guests up to the edge of a peak in the escarpment mountains and unveils a sight that will stay with them forever. The view [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10068,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[132],"tags":[],"class_list":["post-10065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-current-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/posts\/10065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/comments?post=10065"}],"version-history":[{"count":0,"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/posts\/10065\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/media\/10068"}],"wp:attachment":[{"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/media?parent=10065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/categories?post=10065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kurtsafari.com\/it\/wp-json\/wp\/v2\/tags?post=10065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}