{"id":9480,"date":"2019-08-04T00:00:00","date_gmt":"2019-08-03T22:00:00","guid":{"rendered":"https:\/\/www.kurtsafari.com\/all-about-the-spotted-hyena\/"},"modified":"2025-05-15T09:55:01","modified_gmt":"2025-05-15T07:55:01","slug":"tout-savoir-sur-la-hyene-tachetee","status":"publish","type":"post","link":"https:\/\/www.kurtsafari.com\/fr\/kruger-national-park-news\/kruger-national-park-animals-guide\/all-about-the-spotted-hyena\/","title":{"rendered":"Tout sur la hy\u00e8ne tachet\u00e9e"},"content":{"rendered":"<h2>Hy\u00e8ne tachet\u00e9e<\/h2>\n<p>L'un des animaux les plus rares que vous aurez l'occasion de croiser lors d'un <a href=\"https:\/\/www.kurtsafari.com\/fr\/\">Safari au parc Kruger<\/a> est la hy\u00e8ne. Ces animaux fascinants se trouvent dans tout le parc et dans ce blog, nous allons partager des informations incontournables.<\/p>\n<p>La hy\u00e8ne mouchet\u00e9e est la hy\u00e8ne que l'on peut voir que l'on peut voir dans le <a href=\"https:\/\/www.kurtsafari.com\/fr\/\">Parc national Kruger<\/a>.Ces animaux \u00e0 l'aspect d\u00e9sordonn\u00e9 n'appartiennent ni \u00e0 la famille des chiens ni \u00e0 celle des chats, ils appartiennent \u00e0 leur propre famille appel\u00e9e, <em>hy\u00e9nid\u00e9s<\/em>.Ils mesurent environ 80 cm au garrot et p\u00e8sent jusqu'\u00e0 60 kg. Leur dos est inclin\u00e9 et ils ont une apparence hirsute et n\u00e9glig\u00e9e. La hy\u00e8ne peut broyer un f\u00e9mur de buffle en un seul mouvement gr\u00e2ce \u00e0 ses m\u00e2choires puissantes. Une hy\u00e8ne affam\u00e9e peut manger jusqu'\u00e0 un tiers de son propre poids.<\/p>\n<p>La hy\u00e8ne tachet\u00e9e a g\u00e9n\u00e9ralement deux petits, qui naissent agressifs. Ils naissent brun fonc\u00e9 avec leurs dents et leurs yeux ouverts. Les petits naissent dans un terrier que la m\u00e8re creuse et y sont gard\u00e9s jusqu'\u00e0 ce qu'ils aient au moins trois semaines. Apr\u00e8s cela, leur fourrure devient plus claire et ils commencent \u00e0 d\u00e9velopper des taches.<\/p>\n<p>Les hy\u00e8nes chassent et se nourrissent de charognes la nuit. Les hy\u00e8nes sont des carnivores, opportunistes pour la plupart. Si les hy\u00e8nes sont le pr\u00e9dateur dominant dans une r\u00e9gion, elles chassent leurs propres proies, mais s'il y a d'autres pr\u00e9dateurs dans la r\u00e9gion, elles ont tendance \u00e0 se nourrir de charognes. Sans crainte, elles tenteront de voler de la nourriture \u00e0 d'autres pr\u00e9dateurs, souvent au prix de leur vie. Lorsque les hy\u00e8nes chassent, c'est g\u00e9n\u00e9ralement en meute, recherchant astucieusement les plus faibles du troupeau, puis l'isolant avant de le poursuivre sans rel\u00e2che sur plusieurs kilom\u00e8tres, jusqu'\u00e0 ce que la proie soit totalement \u00e9puis\u00e9e. \u00c0 ce stade, la meute de hy\u00e8nes abattra l'animal et l'\u00e9visc\u00e9rera. En meute, les hy\u00e8nes s'attaquent au gros gibier, z\u00e8bres ou koudous, mais si elles chassent seules, elles chassent des animaux plus petits comme des babouins ou des pintades. Les lions et les hy\u00e8nes se d\u00e9testent, et s'entretuent souvent leurs petits ou leurs faibles. Bien que les hy\u00e8nes redoutent les lions, elles n'ont pas peur des lionnes et volent facilement une proie \u00e0 une lionne en l'absence de lions. Surveillant le ciel \u00e0 la recherche de vautours qui encerclent une carcasse, ces animaux rus\u00e9s s'envolent alors pour trouver la proie. En p\u00e9riode de s\u00e9cheresse, des hy\u00e8nes ont \u00e9t\u00e9 vues mangeant des poissons qui meurent dans les points d'eau qui s'ass\u00e8chent.<\/p>\n<p>La hy\u00e8ne \u201c rit \u201d hyst\u00e9riquement, gloussant d'une mani\u00e8re \u00e9trange, presque humaine, tout \u00e0 fait \u00e0 l'oppos\u00e9 du rugissement puissant du lion. Au Moyen \u00c2ge, on croyait que la hy\u00e8ne d\u00e9terrait les cadavres pour les manger. Dans certaines cultures, on pense qu'elles poss\u00e8dent des pouvoirs magiques et qu'elles appartiennent aux sorci\u00e8res. On croit qu'elles sont le b\u00e9tail des sorci\u00e8res et qu'elles sortent la nuit avec elles. Dans certains folklores, si un enfant na\u00eet la nuit pendant que la hy\u00e8ne crie, cet enfant deviendra un voleur. Une autre tribu en Afrique croit que si vous voulez que votre enfant marche t\u00f4t, vous devez vous assurer que l'enfant a de la bouse de hy\u00e8ne quelque part sur lui.<\/p>\n<h3><strong>Bien qu'ils ne soient pas toujours aper\u00e7us au quotidien, plus vous passerez de temps dans le Kruger, plus vous aurez d'occasions de les voir. R\u00e9servez votre <a href=\"https:\/\/www.kurtsafari.com\/fr\/\">Safari dans le parc national Kruger<\/a> aujourd'hui. <\/strong><\/h3>","protected":false},"excerpt":{"rendered":"<p>Spotted Hyena One of the more rare animals you\u2019ll have the opportunity of coming across during a Kruger Park safari is the hyena. These fascinating animals are found all over the park and in this blog we\u2019re going to share some of the must know information. The Spotted Hyena is the hyena that can be [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[117],"tags":[],"class_list":["post-9480","post","type-post","status-publish","format-standard","hentry","category-kruger-animal-tour-guide"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kurtsafari.com\/fr\/wp-json\/wp\/v2\/posts\/9480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kurtsafari.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kurtsafari.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kurtsafari.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kurtsafari.com\/fr\/wp-json\/wp\/v2\/comments?post=9480"}],"version-history":[{"count":0,"href":"https:\/\/www.kurtsafari.com\/fr\/wp-json\/wp\/v2\/posts\/9480\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kurtsafari.com\/fr\/wp-json\/wp\/v2\/media?parent=9480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kurtsafari.com\/fr\/wp-json\/wp\/v2\/categories?post=9480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kurtsafari.com\/fr\/wp-json\/wp\/v2\/tags?post=9480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}